{"id":754,"date":"2017-02-03T16:36:53","date_gmt":"2017-02-03T15:36:53","guid":{"rendered":"http:\/\/drawingserendipities.com\/art-blog\/?p=754"},"modified":"2017-02-22T14:07:38","modified_gmt":"2017-02-22T13:07:38","slug":"stories-behind-the-paintingshuman-nature-and-new-years-resolutions","status":"publish","type":"post","link":"http:\/\/drawingserendipities.com\/art-blog\/es\/2017\/02\/stories-behind-the-paintingshuman-nature-and-new-years-resolutions\/","title":{"rendered":"<span class=\"small-text\">Historias detr\u00e1s de las obras:<\/span><br \/>La naturaleza humana y resoluciones de a\u00f1o nuevo"},"content":{"rendered":"<p><a href=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-756\" src=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight-585x809.jpg\" alt=\"2017 Resoluci\u00f3n de a\u00f1o nuevo: volar alto como un p\u00e1jaro. Comencemos por el pico. D\u00e9jame hacer bien la parte del p\u00e1jaro primero.\" width=\"585\" height=\"809\" srcset=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight-585x809.jpg 585w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight-90x125.jpg 90w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight-181x250.jpg 181w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight-768x1063.jpg 768w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight-624x863.jpg 624w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-GetTheBirdPartRight.jpg 800w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/a>\u00bfQueda algo de nuestras resoluciones de a\u00f1o nuevo, ahora que Enero se termin\u00f3?<br \/>\nYo realic\u00e9 este y el cuadro de abajo con pinturas acr\u00edlicas en Enero de 2017- hace unos d\u00edas &#8211; en una \u00e9poca en la que muchos de nosotros lanzamos una mirada hacia el a\u00f1o que se fue pero tambi\u00e9n miramos al a\u00f1o que comienza con nuevas expectativas y nuevos proyectos<\/p>\n<p><strong>\u201cD\u00e9jame hacer bien la parte del p\u00e1jaro primero\u201d<\/strong> (el cuadro de arriba) se trata de re\u00edrme un poco de mi misma y de esta tendencia humana de concentrarse en nimiedades en lugar de \u201cagarrar al toro por los cuernos\u201d. \u00bfTe haz visto haciendo lo mismo?<\/p>\n<p>Yo s\u00ed. Por ejemplo, yo comenc\u00e9 a publicar mis dibujos diarios en Instagram en Agosto de 2016, pero no toqu\u00e9 el programa hasta despu\u00e9s de haber hecho un cursillo acerca del programa, despu\u00e9s de haber le\u00eddo entrevistas de gente que lo usa exitosamente, despu\u00e9s de haber hablado con algunos usuarios y despu\u00e9s de haber le\u00eddo manuales de uso&#8230; me causa gracia! Pero esa soy yo, me asustan los medios de redes sociales. Imag\u00ednate, no toqu\u00e9 el programa en un a\u00f1o.<\/p>\n<blockquote><p><strong>\u201cHay que agarrar al toro por los cuernos\u201d<\/strong> Trato de recordar esto cuando quiero mantenerme concentrada en lo que es importante.<\/p><\/blockquote>\n<p><a href=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-757\" src=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut-585x437.jpg\" alt=\"Resoluci\u00f3n de a\u00f1o nuevo: detener esta pelea que hay dentro de mi cabeza. P\u00e1same los guantes de boxeo! A sacarla a golpes!\" width=\"585\" height=\"437\" srcset=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut-585x437.jpg 585w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut-125x93.jpg 125w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut-250x187.jpg 250w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut-768x574.jpg 768w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut-624x466.jpg 624w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-AcrylicPainting-PunchItOut.jpg 925w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/a><strong>Con el cuadro \u201cSacarla a golpes\u201d me pregunto:<\/strong><br \/>\n<strong> \u201cInformarse y buscar entendimiento o reaccionar con miedo de manera ciega?\u201d<\/strong><br \/>\nEsto es algo que estamos viviendo a menudo hoy en d\u00eda en nuestro planeta. Pelear la violencia con violencia y el odio con odio. Como Martin Luther King dijo una vez:<\/p>\n<p><a href=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-763\" src=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es-585x585.jpg\" alt=\"\u201cLa oscuridad no puede expulsar la oscuridad, s\u00f3lo la luz puede hacer eso. El odio no puede expulsar el odio, s\u00f3lo el amor puede hacer eso.\u201d -Martin Luther King Jr.\" width=\"585\" height=\"585\" srcset=\"http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es-585x585.jpg 585w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es-125x125.jpg 125w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es-250x250.jpg 250w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es-768x768.jpg 768w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es-624x624.jpg 624w, http:\/\/drawingserendipities.com\/art-blog\/wp-content\/uploads\/2017\/02\/Atamayka-MLKQuote-es.jpg 800w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/a><\/p>\n<p><strong>+ (Nota: Todas las obras est\u00e1n disponibles. Para obtener detalles, por favor toma contacto conmigo a trav\u00e9s de <a href=\"mailto:art@atamayka.com\">art@atamayka.com<\/a>) +<\/strong><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 32px; left: 40px;\">Merken<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 1938px; left: 40px;\">Merken<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer;\">Merken<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c  no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 1938px; left: 40px;\">Merken<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfQueda algo de nuestras resoluciones de a\u00f1o nuevo, ahora que Enero se termin\u00f3? Yo realic\u00e9 este y el cuadro de abajo con pinturas acr\u00edlicas en Enero de 2017- hace unos d\u00edas &#8211; en una \u00e9poca en la que muchos de nosotros lanzamos una mirada hacia el a\u00f1o que se fue pero tambi\u00e9n miramos al a\u00f1o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,35,10,3,9],"tags":[],"class_list":["post-754","post","type-post","status-publish","format-standard","hentry","category-acrylics","category-artist-process","category-living-with-art","category-painting","category-story"],"_links":{"self":[{"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/posts\/754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/comments?post=754"}],"version-history":[{"count":15,"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/posts\/754\/revisions"}],"predecessor-version":[{"id":827,"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/posts\/754\/revisions\/827"}],"wp:attachment":[{"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/media?parent=754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/categories?post=754"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/drawingserendipities.com\/art-blog\/es\/wp-json\/wp\/v2\/tags?post=754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}